{"id":94,"date":"2023-02-14T11:25:26","date_gmt":"2023-02-14T10:25:26","guid":{"rendered":"https:\/\/praktiska.se\/stockholm-liljeholmen\/?page_id=94"},"modified":"2025-02-17T13:28:52","modified_gmt":"2025-02-17T12:28:52","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/","title":{"rendered":"Kontakta oss"},"content":{"rendered":"\n\t<div class=\"module_wrapper ams_remote_pages_module \">\n\t\t\n\t\n\t\n<section  class=\"ams-map ams-map--fifty c-block  media-bottom media-right \" data-color-scheme=\"karta-gra\" data-locations=\"[{&quot;id&quot;:&quot;3352&quot;,&quot;county&quot;:&quot;Stockholms l\\u00e4n&quot;,&quot;city&quot;:&quot;Stockholms stad&quot;,&quot;school&quot;:&quot;Stockholm Liljeholmen&quot;,&quot;title&quot;:&quot;Praktiska Gymnasiet Stockholm Liljeholmen&quot;,&quot;phone&quot;:&quot;086340137&quot;,&quot;phone_formatted&quot;:&quot;08-6340137&quot;,&quot;email&quot;:&quot;liljeholmen@praktiska.se&quot;,&quot;visiting_address&quot;:{&quot;address&quot;:&quot;L\\u00f6vholmsv\\u00e4gen 2, plan 5&quot;,&quot;zip_code&quot;:&quot;117 43&quot;,&quot;city&quot;:&quot;Stockholm&quot;},&quot;postal_address&quot;:{&quot;address&quot;:&quot;L\\u00f6vholmsv\\u00e4gen 2&quot;,&quot;zip_code&quot;:&quot;117 43&quot;,&quot;city&quot;:&quot;Stockholm&quot;},&quot;address_map&quot;:&quot;L\\u00f6vholmsv\\u00e4gen 2, Stockholm, Sverige&quot;,&quot;lat&quot;:59.3128651,&quot;lng&quot;:18.0243465,&quot;link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/praktiska.se\\\/stockholm-liljeholmen\\\/&quot;,&quot;text&quot;:&quot;&quot;}}]\">\n\t<div class=\"ams-map__content u-pt-fluid-3xl-6xl u-pb-fluid-3xl-6xl l-stack l-stack-fluid-xl is-left is-left@lg\">\n\t\t\t\n\t<h1\n\tclass=\"c-heading u-font-title-1 \"\n\tstyle=\"\">\n\t\t\n\t\t\t\t\tH\u00e4r finns vi\n\t\t\t\t\n\t<\/h1>\n\n\t\t\n\t\t\t\t\t<div class=\"contact-info l-stack\">\n\t\t\t\t\t\t\t\t\t<div class=\"contact-info__item\">\n\t\t\t\t\t\t<p class=\"contact-info__heading u-font-title-4\">\n\t\t\t\t\t\t\tBes\u00f6ksadress\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tL\u00f6vholmsv\u00e4gen 2, plan 5<br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t117 43 Stockholm\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"contact-info__item\">\n\t\t\t\t\t\t<p class=\"contact-info__heading u-font-title-4\">\n\t\t\t\t\t\t\tKontakt\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:086340137\">08-6340137<\/a><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:liljeholmen@praktiska.se\">liljeholmen@praktiska.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<div class=\"ams-map__media\">\n\t<\/div>\n<\/section>\n\t<\/div>\n\n\t\n\n\n<section \n\t\t class=\"\n\t\t ams-contact\n\t\t \n\t\t c-block l-stacked\n\t\t \n\t\t \n\t\t js-load-more\n\t\t \"\n\t\t data-color-scheme=\"white\"\n\t\t\t\t\tdata-count=\"50\"\n\t\t\t\t\t\t\tdata-count-mobile=\"2\"\n\t\t\t\t>\n\t<div\n\t\t class=\"\n\t\t l-container\n\t\t l-stack l-stack-fluid-2xl\n\t\t u-pt-fluid-3xl-6xl\n\t\t u-pb-fluid-3xl-6xl\n\t\t is-center\n\t\t is-center@md\n\t\t \">\n\t\t\t\t\t<div class=\"ams-contact__intro l-stack l-stack-lg\">\n\t\t\t\t\t\n\t<h2\n\tclass=\"c-heading u-font-title-1 \"\n\tstyle=\"\">\n\t\t\n\t\t\t\t\tLedning\n\t\t\t\t\n\t<\/h2>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t    \t\n\t\t\n\t\t<ul\n\t\t\tid=\"contact-grid-6a573d27f10f2\"\n\t\t\tclass=\"ams-contact__list l-grid u-gap-fluid-2xl-4xl u-justify-center js-results \"\n\t\t\taria-label=\"Kontakter\"\n\t\t\tdata-filter-animation=\"off\"\n\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"ledning\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tJessica Samuelsson\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Rektor<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0702938079\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-293 80 79<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"mailto:jes&#115;&#105;ca.&#115;&#097;m&#117;els&#115;&#111;n&#064;&#112;r&#097;ktisk&#097;.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">jessic&#097;&#046;&#115;&#097;&#109;u&#101;&#108;&#115;&#115;&#111;n&#064;&#112;rak&#116;&#105;&#115;&#107;&#097;.&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"384\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/02\/jessica-400x384.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personfoto\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/02\/jessica-400x384.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/02\/jessica-300x288.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/02\/jessica-600x576.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/02\/jessica-800x769.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/02\/jessica-1024x984.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/02\/jessica-1200x1153.jpg 1200w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"ledning\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tCamilla Narvehed\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Bitr\u00e4dande rektor<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0706151980\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-615 19 80<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;&#105;l&#116;&#111;&#058;&#099;&#097;mi&#108;&#108;a&#046;n&#097;&#114;&#118;e&#104;e&#100;&#064;&#112;rak&#116;is&#107;a.se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#099;a&#109;illa&#046;n&#097;&#114;v&#101;h&#101;&#100;&#064;&#112;r&#097;&#107;t&#105;ska&#046;s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"459\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/03\/img2846-scaled-e1767638286966-400x459.jpeg\" class=\"u-radius-round u-ratio-landscape\" alt=\"\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/03\/img2846-scaled-e1767638286966-400x459.jpeg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/03\/img2846-scaled-e1767638286966-300x344.jpeg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/03\/img2846-scaled-e1767638286966-600x689.jpeg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/03\/img2846-scaled-e1767638286966-800x918.jpeg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/03\/img2846-scaled-e1767638286966-1024x1175.jpeg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/03\/img2846-scaled-e1767638286966-1200x1377.jpeg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/03\/img2846-scaled-e1767638286966.jpeg 1517w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa ledning\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tCaroline Sj\u00f6kvist\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Bitr\u00e4dande rektor &amp; Specialpedagog<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0702309244\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">0702-309244  <\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;il&#116;o:caro&#108;&#105;n&#101;&#046;&#115;&#106;ok&#118;is&#116;&#064;p&#114;&#097;&#107;&#116;&#105;s&#107;&#097;.se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">c&#097;&#114;o&#108;&#105;&#110;&#101;&#046;sjo&#107;&#118;&#105;s&#116;&#064;&#112;&#114;&#097;k&#116;is&#107;&#097;.&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"413\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-400x413.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-400x413.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-300x310.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-600x620.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-800x826.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-1024x1057.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-1200x1239.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t\n\t\t    <div class=\"ams-contact__more u-inline-items js-load-more-btn\">\n        <button href=\"#\"\n                class=\"c-btn\"\n                data-style=\"round\"\n                data-size=\"md\"\n                data-width=\"full-mobile\"\n                data-variant=\"outline\">\n        \tVisa mer\n        <\/button>\n    <\/div>\n\n\t\t\t<\/div>\n\n\t\t\n\n<\/section>\n\n\n\n<section \n\t\t class=\"\n\t\t ams-contact\n\t\t \n\t\t c-block l-stacked\n\t\t \n\t\t \n\t\t js-load-more\n\t\t \"\n\t\t data-color-scheme=\"white\"\n\t\t\t\t\tdata-count=\"50\"\n\t\t\t\t\t\t\tdata-count-mobile=\"2\"\n\t\t\t\t>\n\t<div\n\t\t class=\"\n\t\t l-container\n\t\t l-stack l-stack-fluid-2xl\n\t\t u-pt-fluid-3xl-6xl\n\t\t u-pb-fluid-3xl-6xl\n\t\t is-center\n\t\t is-center@md\n\t\t \">\n\t\t\t\t\t<div class=\"ams-contact__intro l-stack l-stack-lg\">\n\t\t\t\t\t\n\t<h2\n\tclass=\"c-heading u-font-title-1 \"\n\tstyle=\"\">\n\t\t\n\t\t\t\t\tAdministration\n\t\t\t\t\n\t<\/h2>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t    \t\n\t\t\n\t\t<ul\n\t\t\tid=\"contact-grid-6a573d2805d33\"\n\t\t\tclass=\"ams-contact__list l-grid u-gap-fluid-2xl-4xl u-justify-center js-results \"\n\t\t\taria-label=\"Kontakter\"\n\t\t\tdata-filter-animation=\"off\"\n\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"administration\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tSanna Lindstr\u00f6m\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Kontraktsadministrat\u00f6r, Marknadsansvarig<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0735863935\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">073-586 39 35<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"ma&#105;l&#116;&#111;&#058;s&#097;&#110;&#110;a.lin&#100;s&#116;rom&#064;&#112;&#114;&#097;k&#116;is&#107;a.&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">sanna.l&#105;n&#100;&#115;&#116;rom&#064;praktisk&#097;&#046;&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"243\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/sanna-lindstrom.jpeg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"administration elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tEsmeralda Wall\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Skolkoordinator &amp; APL-samordnare<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0706430551\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-643 05 51<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"mail&#116;&#111;&#058;esm&#101;&#114;&#097;&#108;d&#097;.&#119;all&#064;prakti&#115;&#107;&#097;&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">es&#109;era&#108;d&#097;.w&#097;&#108;&#108;&#064;&#112;raktiska.&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"513\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-400x513.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-400x513.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-300x385.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-600x770.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-800x1027.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-1024x1314.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-1200x1540.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"administration elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tHelena Andersson\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Skoladministrat\u00f6r &amp; Internationaliseringsansvarig<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761016523\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-101 65 23<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;&#105;lt&#111;:h&#101;l&#101;n&#097;&#046;a&#110;d&#101;r&#115;&#115;&#111;n&#064;pr&#097;&#107;ti&#115;k&#097;&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#104;&#101;len&#097;.andersson&#064;&#112;r&#097;k&#116;&#105;sk&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"503\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-400x503.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-400x503.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-300x377.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-600x754.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-800x1006.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-1024x1287.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-1200x1509.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"administration elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tMax Nordin\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Skolbibliotekarie &amp; Vaktm\u00e4stare<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0767729298\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-772 92 98<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;&#105;&#108;t&#111;:&#109;&#097;&#120;.n&#111;rd&#105;&#110;&#064;p&#114;&#097;&#107;&#116;i&#115;ka.se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#109;&#097;&#120;&#046;no&#114;din&#064;&#112;ra&#107;ti&#115;&#107;&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"467\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-400x467.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-400x467.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-300x351.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-600x701.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-800x935.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-1024x1197.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-1200x1402.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t\n\t\t    <div class=\"ams-contact__more u-inline-items js-load-more-btn\">\n        <button href=\"#\"\n                class=\"c-btn\"\n                data-style=\"round\"\n                data-size=\"md\"\n                data-width=\"full-mobile\"\n                data-variant=\"outline\">\n        \tVisa mer\n        <\/button>\n    <\/div>\n\n\t\t\t<\/div>\n\n\t\t\n\n<\/section>\n\n\n\n<section \n\t\t class=\"\n\t\t ams-contact\n\t\t \n\t\t c-block l-stacked\n\t\t \n\t\t \n\t\t js-load-more\n\t\t \"\n\t\t data-color-scheme=\"white\"\n\t\t\t\t\tdata-count=\"50\"\n\t\t\t\t\t\t\tdata-count-mobile=\"2\"\n\t\t\t\t>\n\t<div\n\t\t class=\"\n\t\t l-container\n\t\t l-stack l-stack-fluid-2xl\n\t\t u-pt-fluid-3xl-6xl\n\t\t u-pb-fluid-3xl-6xl\n\t\t is-center\n\t\t is-center@md\n\t\t \">\n\t\t\t\t\t<div class=\"ams-contact__intro l-stack l-stack-lg\">\n\t\t\t\t\t\n\t<h2\n\tclass=\"c-heading u-font-title-1 \"\n\tstyle=\"\">\n\t\t\n\t\t\t\t\t\u00c4mnesl\u00e4rare\n\t\t\t\t\n\t<\/h2>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t    \t\n\t\t\n\t\t<ul\n\t\t\tid=\"contact-grid-6a573d281059f\"\n\t\t\tclass=\"ams-contact__list l-grid u-gap-fluid-2xl-4xl u-justify-center js-results \"\n\t\t\taria-label=\"Kontakter\"\n\t\t\tdata-filter-animation=\"off\"\n\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tJohanna Andersson\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Svenska<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0722221404\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">072-222 14 04<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;a&#105;&#108;&#116;&#111;:j&#111;h&#097;n&#110;a&#046;&#097;n&#100;ers&#115;&#111;&#110;&#064;&#112;r&#097;kt&#105;&#115;&#107;a&#046;&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#106;&#111;&#104;an&#110;&#097;.and&#101;&#114;&#115;s&#111;n&#064;&#112;&#114;&#097;kt&#105;&#115;k&#097;&#046;se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"535\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926154308-scaled-e1729088264279-400x535.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926154308-scaled-e1729088264279-400x535.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926154308-scaled-e1729088264279-300x401.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926154308-scaled-e1729088264279-600x802.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926154308-scaled-e1729088264279-800x1070.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926154308-scaled-e1729088264279-1024x1369.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926154308-scaled-e1729088264279-1200x1604.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926154308-scaled-e1729088264279.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tMalek Kalhitmrawe\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Engelska &amp; Historia<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0726833661\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">072-683 36 61<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;&#105;l&#116;o:&#109;&#097;lek.ka&#108;&#104;&#105;&#116;mra&#119;e&#064;&#112;&#114;ak&#116;i&#115;ka&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">m&#097;&#108;&#101;&#107;.&#107;&#097;&#108;h&#105;tmr&#097;&#119;e&#064;p&#114;a&#107;t&#105;s&#107;a.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"493\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241008141734-scaled-e1729088171240-400x493.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241008141734-scaled-e1729088171240-400x493.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241008141734-scaled-e1729088171240-300x370.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241008141734-scaled-e1729088171240-600x740.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241008141734-scaled-e1729088171240-800x987.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241008141734-scaled-e1729088171240-1024x1263.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241008141734-scaled-e1729088171240-1200x1480.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241008141734-scaled-e1729088171240.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tMartin Kiersz\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Idrott &amp; h\u00e4lsa<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761498376\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-149 83 76<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;i&#108;t&#111;&#058;marti&#110;.ki&#101;rs&#122;&#064;p&#114;a&#107;t&#105;&#115;k&#097;.se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">marti&#110;.kie&#114;sz&#064;&#112;&#114;&#097;&#107;tisk&#097;.&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"495\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241014150202-scaled-e1729253029382-400x495.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241014150202-scaled-e1729253029382-400x495.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241014150202-scaled-e1729253029382-300x371.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241014150202-scaled-e1729253029382-600x742.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241014150202-scaled-e1729253029382-800x989.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241014150202-scaled-e1729253029382-1024x1266.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241014150202-scaled-e1729253029382-1200x1484.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241014150202-scaled-e1729253029382.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tNour Mercho\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Matematik<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;ai&#108;t&#111;&#058;n&#111;&#117;r.&#109;&#101;rcho&#064;pr&#097;&#107;ti&#115;&#107;a&#046;&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#110;&#111;&#117;&#114;.&#109;e&#114;cho&#064;pr&#097;kt&#105;ska.s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"503\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141006-scaled-e1729088112154-400x503.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141006-scaled-e1729088112154-400x503.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141006-scaled-e1729088112154-300x377.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141006-scaled-e1729088112154-600x754.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141006-scaled-e1729088112154-800x1006.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141006-scaled-e1729088112154-1024x1287.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141006-scaled-e1729088112154-1200x1509.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141006-scaled-e1729088112154.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tMattias Moro\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Idrott &amp; h\u00e4lsa, APL-samordnare Fordon &amp; Transport <\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761169985\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-116 99 85<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;&#105;&#108;t&#111;&#058;m&#097;tti&#097;&#115;.&#109;o&#114;o&#064;pr&#097;k&#116;&#105;s&#107;a&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#109;attias&#046;&#109;o&#114;&#111;&#064;prak&#116;&#105;s&#107;&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"479\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135709-scaled-e1729088073968-400x479.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135709-scaled-e1729088073968-400x479.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135709-scaled-e1729088073968-300x359.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135709-scaled-e1729088073968-600x718.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135709-scaled-e1729088073968-800x957.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135709-scaled-e1729088073968-1024x1225.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135709-scaled-e1729088073968-1200x1436.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135709-scaled-e1729088073968.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tAnna Naber\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Engelska<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0767693607\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-769 36 07<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;ailto&#058;a&#110;&#110;a&#107;a&#114;ina&#046;n&#097;be&#114;&#064;pr&#097;kt&#105;&#115;k&#097;.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">an&#110;ak&#097;ri&#110;a.&#110;&#097;b&#101;r&#064;&#112;&#114;a&#107;t&#105;&#115;k&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"487\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094810-scaled-e1729088012682-400x487.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094810-scaled-e1729088012682-400x487.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094810-scaled-e1729088012682-300x366.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094810-scaled-e1729088012682-600x731.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094810-scaled-e1729088012682-800x975.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094810-scaled-e1729088012682-1024x1248.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094810-scaled-e1729088012682-1200x1462.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094810-scaled-e1729088012682.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tPeter Nordstr\u00f6m\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Samh\u00e4llskunskap<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;i&#108;&#116;&#111;&#058;&#112;&#101;&#116;er&#046;&#110;o&#114;&#100;&#115;tr&#111;m&#064;p&#114;aktis&#107;a&#046;&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#112;&#101;&#116;&#101;r&#046;n&#111;r&#100;&#115;&#116;&#114;o&#109;&#064;&#112;&#114;&#097;&#107;ti&#115;ka&#046;se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"438\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930150044-scaled-e1729087971752-400x438.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930150044-scaled-e1729087971752-400x438.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930150044-scaled-e1729087971752-300x328.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930150044-scaled-e1729087971752-600x657.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930150044-scaled-e1729087971752-800x875.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930150044-scaled-e1729087971752-1024x1121.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930150044-scaled-e1729087971752-1200x1313.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930150044-scaled-e1729087971752.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tJohanna Piel\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Svenska som andraspr\u00e5k<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0722079550\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">072-207 95 50<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;&#105;lt&#111;:joha&#110;&#110;a&#046;piel&#064;p&#114;ak&#116;iska.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#106;o&#104;a&#110;&#110;a.&#112;&#105;&#101;&#108;&#064;p&#114;&#097;kti&#115;&#107;&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"495\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926151931-scaled-e1729087929563-400x495.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926151931-scaled-e1729087929563-400x495.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926151931-scaled-e1729087929563-300x371.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926151931-scaled-e1729087929563-600x742.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926151931-scaled-e1729087929563-800x989.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926151931-scaled-e1729087929563-1024x1266.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926151931-scaled-e1729087929563-1200x1484.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926151931-scaled-e1729087929563.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tAgnieszka Placheta\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Matematik<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761351534\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-135 15 34<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;&#105;&#108;&#116;&#111;:&#097;gn&#105;es&#122;k&#097;.&#112;lach&#101;&#116;a&#064;prak&#116;&#105;&#115;ka&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#097;g&#110;i&#101;&#115;&#122;k&#097;.&#112;&#108;ach&#101;t&#097;&#064;&#112;r&#097;&#107;ti&#115;ka&#046;&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"447\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925144408-scaled-e1729087865360-400x447.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925144408-scaled-e1729087865360-400x447.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925144408-scaled-e1729087865360-300x335.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925144408-scaled-e1729087865360-600x671.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925144408-scaled-e1729087865360-800x894.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925144408-scaled-e1729087865360-1024x1145.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925144408-scaled-e1729087865360-1200x1341.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925144408-scaled-e1729087865360.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tSofia S\u00f6derstr\u00f6m\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Engelska<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0751383121\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">075-138 31 21<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;&#105;&#108;&#116;&#111;:&#115;o&#102;&#105;&#097;&#046;&#115;o&#100;&#101;&#114;&#115;&#116;ro&#109;&#064;&#112;r&#097;ktiska&#046;&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">s&#111;fia.&#115;&#111;&#100;e&#114;&#115;t&#114;&#111;m&#064;&#112;&#114;a&#107;&#116;&#105;&#115;&#107;&#097;&#046;&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"320\" height=\"383\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/bild-saknas-e1771939429212.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/bild-saknas-e1771939429212.jpg 320w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/bild-saknas-e1771939429212-300x359.jpg 300w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tLinda Ullman\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Naturkunskap<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761017802\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-101 78 02<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"mailto:&#108;&#105;n&#100;a.&#117;l&#108;&#109;an&#064;&#112;rak&#116;&#105;ska.s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">l&#105;&#110;&#100;a&#046;&#117;&#108;&#108;ma&#110;&#064;prak&#116;i&#115;ka&#046;s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"607\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241011141007-scaled-e1729087785255-400x607.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241011141007-scaled-e1729087785255-400x607.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241011141007-scaled-e1729087785255-300x455.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241011141007-scaled-e1729087785255-600x910.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241011141007-scaled-e1729087785255-800x1214.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241011141007-scaled-e1729087785255-1024x1554.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241011141007-scaled-e1729087785255-1200x1821.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241011141007-scaled-e1729087785255.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tLottie Hansen\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Svenska och svenska som andraspr\u00e5k<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"240\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/2023\/11\/kontactplaceholder.png\" class=\"u-radius-round u-ratio-landscape\" alt=\"Avatarbild\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tAlice Bolk\u00e9us\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Matematik<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"240\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/2023\/11\/kontactplaceholder.png\" class=\"u-radius-round u-ratio-landscape\" alt=\"Avatarbild\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tMaria Jonsson\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Idrott &amp; H\u00e4lsa, APL Barn &amp; Fritid<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0763187345\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-318 73 45<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"mai&#108;to&#058;m&#097;&#114;ia.jo&#110;&#115;s&#111;&#110;2&#064;&#112;r&#097;&#107;&#116;i&#115;ka&#046;se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">maria&#046;j&#111;&#110;s&#115;on&#050;&#064;&#112;ra&#107;ti&#115;&#107;&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"449\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120349-scaled-e1729086540613-400x449.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120349-scaled-e1729086540613-400x449.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120349-scaled-e1729086540613-300x336.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120349-scaled-e1729086540613-600x673.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120349-scaled-e1729086540613-800x897.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120349-scaled-e1729086540613-1024x1148.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120349-scaled-e1729086540613-1200x1346.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120349-scaled-e1729086540613.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tJaana Alm\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Svenska<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:743983088\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">74-398 30 88<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;ilt&#111;:jaan&#097;.&#097;l&#109;&#064;pr&#097;&#107;t&#105;&#115;&#107;a.&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#106;a&#097;&#110;&#097;&#046;&#097;lm&#064;p&#114;&#097;&#107;&#116;iska.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"451\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925153510-scaled-e1729086217518-400x451.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925153510-scaled-e1729086217518-400x451.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925153510-scaled-e1729086217518-300x338.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925153510-scaled-e1729086217518-600x676.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925153510-scaled-e1729086217518-800x902.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925153510-scaled-e1729086217518-1024x1154.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925153510-scaled-e1729086217518-1200x1352.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925153510-scaled-e1729086217518.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tDeser\u00e9 Gullberg Husberg\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Svenska <\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0704004951\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-400 49 51<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;a&#105;lt&#111;&#058;de&#115;&#101;&#114;e&#046;g&#117;ll&#098;&#101;rg&#046;h&#117;s&#098;e&#114;g&#064;p&#114;akti&#115;ka&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#100;&#101;&#115;e&#114;&#101;.&#103;ul&#108;b&#101;&#114;g&#046;hus&#098;&#101;r&#103;&#064;&#112;&#114;a&#107;t&#105;ska&#046;&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"453\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930155303-scaled-e1729088216338-400x453.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930155303-scaled-e1729088216338-400x453.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930155303-scaled-e1729088216338-300x340.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930155303-scaled-e1729088216338-600x680.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930155303-scaled-e1729088216338-800x907.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930155303-scaled-e1729088216338-1024x1160.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930155303-scaled-e1729088216338-1200x1360.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930155303-scaled-e1729088216338.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tMichael Lindfors\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Engelska &amp; F\u00f6rs\u00e4ljning och Service (f\u00f6r\u00e4ldraledig)<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0766397066\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-639 70 66<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;ilto&#058;micha&#101;&#108;.li&#110;&#100;&#102;or&#115;&#064;&#112;&#114;&#097;k&#116;i&#115;ka&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">mi&#099;h&#097;e&#108;&#046;l&#105;&#110;&#100;&#102;o&#114;&#115;&#064;&#112;&#114;akti&#115;&#107;&#097;&#046;&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"427\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-400x427.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-400x427.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-300x320.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-600x641.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-800x854.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-1024x1094.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-1200x1282.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tChristian Liljeros\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Samh\u00e4llskunskap<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0760376193\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-037 61 93<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;i&#108;t&#111;:carl&#099;h&#114;i&#115;&#116;i&#097;&#110;&#046;li&#108;&#106;ero&#115;&#064;pra&#107;&#116;&#105;&#115;k&#097;.se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#099;&#097;rl&#099;&#104;r&#105;s&#116;&#105;a&#110;.&#108;i&#108;j&#101;r&#111;s&#064;pra&#107;&#116;&#105;&#115;k&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"441\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/smartselect20240924154451gallery-e1729085988561-400x441.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/smartselect20240924154451gallery-e1729085988561-400x441.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/smartselect20240924154451gallery-e1729085988561-300x331.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/smartselect20240924154451gallery-e1729085988561-600x662.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/smartselect20240924154451gallery-e1729085988561-800x882.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/smartselect20240924154451gallery-e1729085988561.jpg 1019w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tPeter Achaladaya Milton\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Religion och Larm- &amp; s\u00e4kerhetsteknik<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761384933\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-138 49 33<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;&#105;&#108;to&#058;pet&#101;r&#046;&#109;il&#116;&#111;n&#064;pra&#107;&#116;i&#115;&#107;&#097;&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">p&#101;te&#114;&#046;mi&#108;to&#110;&#064;p&#114;&#097;k&#116;is&#107;a&#046;&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"478\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-400x478.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-400x478.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-300x358.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-600x717.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-800x956.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-1024x1224.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-1200x1434.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tCamilla Steinholtz\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Religion &amp; Naturkunskap<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0767617165\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-761 71 65<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;ilto:&#099;&#097;&#109;il&#108;a.ste&#105;&#110;ho&#108;tz&#064;p&#114;&#097;ktis&#107;a.&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">ca&#109;il&#108;a&#046;&#115;te&#105;&#110;&#104;o&#108;tz&#064;pr&#097;k&#116;&#105;ska&#046;&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"405\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154126-scaled-e1729086272374-400x405.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154126-scaled-e1729086272374-400x405.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154126-scaled-e1729086272374-300x304.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154126-scaled-e1729086272374-600x607.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154126-scaled-e1729086272374-800x809.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154126-scaled-e1729086272374-1024x1036.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154126-scaled-e1729086272374-1200x1214.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154126-scaled-e1729086272374.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tSara Harrami\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Engelska &amp; Religion<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0724523618\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">072-452 36 18<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;&#105;&#108;&#116;&#111;&#058;&#115;ara&#046;harr&#097;&#109;&#105;&#064;&#112;&#114;a&#107;tiska&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#115;&#097;&#114;a.&#104;&#097;r&#114;&#097;&#109;&#105;&#064;p&#114;a&#107;&#116;&#105;&#115;ka&#046;s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"523\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028929-scaled-e1772618806776-400x523.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028929-scaled-e1772618806776-400x523.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028929-scaled-e1772618806776-300x392.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028929-scaled-e1772618806776-600x784.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028929-scaled-e1772618806776-800x1046.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028929-scaled-e1772618806776-1024x1339.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028929-scaled-e1772618806776-1200x1569.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028929-scaled-e1772618806776.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tUlrika Orvedal\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Svenska &amp; Svenska som andraspr\u00e5k<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761019043\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-101 90 43<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;a&#105;l&#116;&#111;&#058;ulrika.o&#114;&#118;&#101;da&#108;&#064;p&#114;akt&#105;&#115;ka.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">ul&#114;&#105;&#107;a&#046;&#111;&#114;vedal&#064;&#112;r&#097;kt&#105;s&#107;&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"534\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241030133847-scaled-e1730366267105-400x534.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241030133847-scaled-e1730366267105-400x534.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241030133847-scaled-e1730366267105-300x400.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241030133847-scaled-e1730366267105-600x801.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241030133847-scaled-e1730366267105-800x1067.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241030133847-scaled-e1730366267105-1024x1366.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241030133847-scaled-e1730366267105-1200x1601.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241030133847-scaled-e1730366267105.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t\n\t\t    <div class=\"ams-contact__more u-inline-items js-load-more-btn\">\n        <button href=\"#\"\n                class=\"c-btn\"\n                data-style=\"round\"\n                data-size=\"md\"\n                data-width=\"full-mobile\"\n                data-variant=\"outline\">\n        \tVisa mer\n        <\/button>\n    <\/div>\n\n\t\t\t<\/div>\n\n\t\t\n\n<\/section>\n\n\n\n<section \n\t\t class=\"\n\t\t ams-contact\n\t\t \n\t\t c-block l-stacked\n\t\t \n\t\t \n\t\t js-load-more\n\t\t \"\n\t\t data-color-scheme=\"white\"\n\t\t\t\t\tdata-count=\"50\"\n\t\t\t\t\t\t\tdata-count-mobile=\"2\"\n\t\t\t\t>\n\t<div\n\t\t class=\"\n\t\t l-container\n\t\t l-stack l-stack-fluid-2xl\n\t\t u-pt-fluid-3xl-6xl\n\t\t u-pb-fluid-3xl-6xl\n\t\t is-center\n\t\t is-center@md\n\t\t \">\n\t\t\t\t\t<div class=\"ams-contact__intro l-stack l-stack-lg\">\n\t\t\t\t\t\n\t<h2\n\tclass=\"c-heading u-font-title-1 \"\n\tstyle=\"\">\n\t\t\n\t\t\t\t\tYrkesl\u00e4rare \n\t\t\t\t\n\t<\/h2>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t    \t\n\t\t\n\t\t<ul\n\t\t\tid=\"contact-grid-6a573d28240f3\"\n\t\t\tclass=\"ams-contact__list l-grid u-gap-fluid-2xl-4xl u-justify-center js-results \"\n\t\t\taria-label=\"Kontakter\"\n\t\t\tdata-filter-animation=\"off\"\n\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tBlesa Aref\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Hantverk, inriktning H\u00e5r- och makeupstylist<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#8211;  <\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;i&#108;t&#111;&#058;&#098;le&#115;a.has&#115;a&#110;k&#097;ri&#109;&#064;&#112;rakt&#105;&#115;k&#097;.&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#098;&#108;&#101;sa&#046;h&#097;s&#115;&#097;&#110;k&#097;r&#105;&#109;&#064;&#112;&#114;akt&#105;&#115;&#107;&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"243\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/blesa-aref.jpeg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tVendel Norlin\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">El &amp; Energi<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761119163\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-11 19 163<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"mai&#108;&#116;&#111;&#058;&#118;&#101;&#110;d&#101;&#108;&#046;&#110;&#111;&#114;&#108;in&#064;prak&#116;iska.se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#118;en&#100;&#101;l&#046;&#110;&#111;&#114;&#108;&#105;&#110;&#064;p&#114;&#097;ktis&#107;a&#046;&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"430\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135147-scaled-e1729087019827-400x430.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135147-scaled-e1729087019827-400x430.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135147-scaled-e1729087019827-300x323.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135147-scaled-e1729087019827-600x645.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135147-scaled-e1729087019827-800x860.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135147-scaled-e1729087019827-1024x1101.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135147-scaled-e1729087019827-1200x1291.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135147-scaled-e1729087019827.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tAnders Butta B\u00f6rjesson\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">El &amp; Energi, APL-samordnare<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0708307902\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-830 79 02<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"ma&#105;l&#116;&#111;:&#097;&#110;&#100;&#101;r&#115;.b&#111;&#114;&#106;&#101;ss&#111;&#110;&#064;&#112;&#114;ak&#116;&#105;s&#107;a&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">a&#110;de&#114;&#115;.&#098;&#111;r&#106;esso&#110;&#064;&#112;r&#097;kti&#115;k&#097;&#046;&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"438\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120300-scaled-e1729087746964-400x438.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120300-scaled-e1729087746964-400x438.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120300-scaled-e1729087746964-300x328.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120300-scaled-e1729087746964-600x657.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120300-scaled-e1729087746964-800x875.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120300-scaled-e1729087746964-1024x1121.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120300-scaled-e1729087746964-1200x1313.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001120300-scaled-e1729087746964.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tRickard Brink\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Fordon &amp; Transport<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0766772604\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-677 26 04<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;il&#116;&#111;&#058;&#114;i&#099;kar&#100;&#046;&#098;rink&#064;&#112;&#114;a&#107;ti&#115;&#107;a&#046;se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#114;ickard&#046;b&#114;&#105;nk&#064;p&#114;&#097;&#107;t&#105;s&#107;&#097;&#046;&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"492\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016135108-scaled-e1729252986830-400x492.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016135108-scaled-e1729252986830-400x492.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016135108-scaled-e1729252986830-300x369.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016135108-scaled-e1729252986830-600x738.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016135108-scaled-e1729252986830-800x984.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016135108-scaled-e1729252986830-1024x1260.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016135108-scaled-e1729252986830-1200x1476.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016135108-scaled-e1729252986830.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tStephan Brink\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Fordon &amp; Transport, APL-ansvarig<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0725755417\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">072-575 54 17<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;a&#105;l&#116;o:&#115;t&#101;p&#104;&#097;&#110;&#046;brink&#064;praktis&#107;a&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">s&#116;ep&#104;an.b&#114;i&#110;&#107;&#064;&#112;rakt&#105;s&#107;&#097;.s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"436\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141241-scaled-e1729171375726-400x436.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141241-scaled-e1729171375726-400x436.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141241-scaled-e1729171375726-300x327.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141241-scaled-e1729171375726-600x653.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141241-scaled-e1729171375726-800x871.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141241-scaled-e1729171375726-1024x1115.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141241-scaled-e1729171375726-1200x1307.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141241-scaled-e1729171375726.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tPutte Eckerstr\u00f6m\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Bygg &amp; Anl\u00e4ggning, M\u00e5leri<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0702092372\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-209 23 72<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;&#105;l&#116;o&#058;p&#117;t&#116;&#101;&#046;&#101;cke&#114;str&#111;&#109;&#064;&#112;&#114;ak&#116;&#105;sk&#097;&#046;se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">pu&#116;te.&#101;c&#107;&#101;&#114;&#115;tro&#109;&#064;pra&#107;t&#105;sk&#097;&#046;s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"511\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016142253-scaled-e1729252938222-400x511.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016142253-scaled-e1729252938222-400x511.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016142253-scaled-e1729252938222-300x383.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016142253-scaled-e1729252938222-600x767.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016142253-scaled-e1729252938222-800x1022.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016142253-scaled-e1729252938222-1024x1309.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016142253-scaled-e1729252938222-1200x1534.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2023\/12\/20241016142253-scaled-e1729252938222.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tJimmy Forsberg\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Bygg &amp; Anl\u00e4ggning<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761136323\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-113 63 23<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;&#105;l&#116;&#111;:ji&#109;m&#121;.f&#111;&#114;&#115;be&#114;g&#064;p&#114;&#097;&#107;t&#105;s&#107;a&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#106;i&#109;my&#046;&#102;&#111;&#114;&#115;b&#101;&#114;g&#064;&#112;r&#097;k&#116;i&#115;ka&#046;s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"473\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135723-scaled-e1729866601460-400x473.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135723-scaled-e1729866601460-400x473.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135723-scaled-e1729866601460-300x355.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135723-scaled-e1729866601460-600x710.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135723-scaled-e1729866601460-800x946.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135723-scaled-e1729866601460-1024x1212.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135723-scaled-e1729866601460.jpg 1196w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tAlissa Gustafsson\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Hotell &amp; turism<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0763101934\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-310 19 34<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"ma&#105;&#108;to&#058;&#097;liss&#097;&#046;gus&#116;a&#102;ss&#111;n&#064;&#112;ra&#107;&#116;&#105;&#115;k&#097;&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">a&#108;i&#115;sa.gusta&#102;&#115;son&#064;p&#114;a&#107;&#116;&#105;s&#107;a&#046;se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"548\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134733-scaled-e1729087702831-400x548.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134733-scaled-e1729087702831-400x548.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134733-scaled-e1729087702831-300x411.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134733-scaled-e1729087702831-600x822.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134733-scaled-e1729087702831-800x1096.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134733-scaled-e1729087702831-1024x1402.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134733-scaled-e1729087702831-1200x1644.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134733-scaled-e1729087702831.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tVicky Hamberg\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Hantverk, inriktning Makeupstylist och F\u00f6rs\u00e4ljning &amp; Service<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761400547\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-140 05 47<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;ai&#108;&#116;&#111;&#058;V&#105;&#099;k&#121;.h&#097;&#109;&#098;&#101;rg&#064;&#112;&#114;&#097;k&#116;&#105;&#115;&#107;&#097;&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">Vic&#107;y.&#104;&#097;&#109;&#098;&#101;rg&#064;&#112;&#114;aktis&#107;a&#046;s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"466\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141441-scaled-e1729087660311-400x466.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141441-scaled-e1729087660311-400x466.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141441-scaled-e1729087660311-300x349.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141441-scaled-e1729087660311-600x699.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141441-scaled-e1729087660311-800x932.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141441-scaled-e1729087660311-1024x1193.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141441-scaled-e1729087660311-1200x1398.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141441-scaled-e1729087660311.jpg 1348w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tPeter H\u00e4llberg\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Industriteknik, inriktning L\u00e5ssmed<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0702416742\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-241 67 42<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;i&#108;&#116;o:p&#101;t&#101;&#114;&#046;ha&#108;lb&#101;&#114;&#103;&#064;&#112;ra&#107;&#116;isk&#097;&#046;&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#112;&#101;&#116;er.&#104;&#097;&#108;l&#098;&#101;r&#103;&#064;&#112;rak&#116;&#105;s&#107;a.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"502\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001104027-scaled-e1729087608405-400x502.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001104027-scaled-e1729087608405-400x502.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001104027-scaled-e1729087608405-300x376.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001104027-scaled-e1729087608405-600x752.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001104027-scaled-e1729087608405-800x1003.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001104027-scaled-e1729087608405-1024x1284.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001104027-scaled-e1729087608405-1200x1505.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001104027-scaled-e1729087608405.jpg 1228w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tRichard Johansen\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Fordon &amp; transport<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0702653418\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-265 34 18<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;ilto:&#114;&#105;&#099;&#104;ard.&#106;&#111;hans&#101;&#110;&#064;&#112;r&#097;ktiska.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#114;&#105;&#099;&#104;a&#114;d.jo&#104;&#097;&#110;se&#110;&#064;&#112;ra&#107;t&#105;&#115;ka.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"541\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141148-scaled-e1729087529892-400x541.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141148-scaled-e1729087529892-400x541.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141148-scaled-e1729087529892-300x406.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141148-scaled-e1729087529892-600x811.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141148-scaled-e1729087529892-800x1081.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141148-scaled-e1729087529892-1024x1384.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004141148-scaled-e1729087529892.jpg 1177w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tAbir Lahdo\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">F\u00f6rs\u00e4ljning &amp; Service<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0730644713\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">073-064 47 13<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;i&#108;&#116;&#111;&#058;&#097;&#098;&#105;r&#046;l&#097;hdo&#064;&#112;ra&#107;&#116;i&#115;ka&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#097;&#098;ir.&#108;ahd&#111;&#064;p&#114;&#097;ktis&#107;a.&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"482\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930153738-scaled-e1729087475995-400x482.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930153738-scaled-e1729087475995-400x482.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930153738-scaled-e1729087475995-300x362.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930153738-scaled-e1729087475995-600x723.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930153738-scaled-e1729087475995-800x964.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930153738-scaled-e1729087475995-1024x1234.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930153738-scaled-e1729087475995-1200x1446.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930153738-scaled-e1729087475995.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tReman Sheaib\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">F\u00f6rs\u00e4ljning &amp; Service<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0730644713\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">073-064 47 13<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;il&#116;&#111;:re&#109;&#097;n&#046;&#115;h&#101;&#097;&#105;b&#064;p&#114;a&#107;tiska&#046;se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">re&#109;&#097;n&#046;s&#104;eai&#098;&#064;&#112;ra&#107;t&#105;&#115;k&#097;.&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"489\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007141523-scaled-e1729087403793-400x489.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007141523-scaled-e1729087403793-400x489.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007141523-scaled-e1729087403793-300x367.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007141523-scaled-e1729087403793-600x733.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007141523-scaled-e1729087403793-800x978.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007141523-scaled-e1729087403793-1024x1251.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007141523-scaled-e1729087403793-1200x1466.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007141523-scaled-e1729087403793.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tClaes S\u00f6derb\u00e4ck\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Industriteknik, inriktning l\u00e5ssmed<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0730933004\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">073-093 30 04<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"mai&#108;t&#111;&#058;c&#108;a&#101;s&#046;so&#100;&#101;r&#098;&#097;ck&#064;p&#114;&#097;k&#116;i&#115;ka.&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">clae&#115;&#046;sode&#114;b&#097;&#099;k&#064;p&#114;akt&#105;&#115;&#107;&#097;.&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"503\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001102409-scaled-e1729087334255-400x503.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001102409-scaled-e1729087334255-400x503.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001102409-scaled-e1729087334255-300x377.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001102409-scaled-e1729087334255-600x754.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001102409-scaled-e1729087334255-800x1005.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001102409-scaled-e1729087334255-1024x1287.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001102409-scaled-e1729087334255-1200x1508.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241001102409-scaled-e1729087334255.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tThomas Sandin\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">El &amp; Energi<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761065591\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-106 55 91<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"ma&#105;l&#116;o:&#116;&#104;&#111;&#109;as&#046;sa&#110;d&#105;n&#064;&#112;r&#097;k&#116;i&#115;ka&#046;&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">th&#111;&#109;&#097;s.sa&#110;d&#105;n&#064;&#112;rak&#116;i&#115;k&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"466\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004142757-scaled-e1729087233320-400x466.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004142757-scaled-e1729087233320-400x466.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004142757-scaled-e1729087233320-300x350.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004142757-scaled-e1729087233320-600x699.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004142757-scaled-e1729087233320-800x933.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004142757-scaled-e1729087233320-1024x1194.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004142757-scaled-e1729087233320-1200x1399.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004142757-scaled-e1729087233320.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tFigen \u00dcnver\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">F\u00f6rs\u00e4ljning &amp; Service<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761351494\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-135 14 94<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;i&#108;t&#111;:&#102;ig&#101;n&#046;u&#110;ver&#064;&#112;rak&#116;is&#107;&#097;&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#102;&#105;g&#101;n&#046;&#117;n&#118;&#101;&#114;&#064;&#112;&#114;akt&#105;ska.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"504\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007133639-scaled-e1729087185784-400x504.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007133639-scaled-e1729087185784-400x504.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007133639-scaled-e1729087185784-300x378.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007133639-scaled-e1729087185784-600x756.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007133639-scaled-e1729087185784-800x1008.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007133639-scaled-e1729087185784-1024x1290.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007133639-scaled-e1729087185784-1200x1512.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007133639-scaled-e1729087185784.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tVeronica Vildma\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Hotell &amp; Turism<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0708283903\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-828 39 03<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;a&#105;lto&#058;ve&#114;on&#105;c&#097;&#046;&#118;&#105;&#108;dma&#064;&#112;&#114;ak&#116;is&#107;a.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">ve&#114;&#111;n&#105;&#099;&#097;&#046;&#118;&#105;&#108;d&#109;&#097;&#064;pr&#097;&#107;t&#105;s&#107;&#097;&#046;&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"496\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134945-scaled-e1729087149967-400x496.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134945-scaled-e1729087149967-400x496.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134945-scaled-e1729087149967-300x372.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134945-scaled-e1729087149967-600x744.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134945-scaled-e1729087149967-800x991.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134945-scaled-e1729087149967-1024x1269.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134945-scaled-e1729087149967-1200x1487.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241007134945-scaled-e1729087149967.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tTony Yousef\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Hantverk, inriktning Fris\u00f6r &amp; H\u00e5rstylist<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761133698\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-113 36 98<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;&#105;l&#116;o:ton&#121;.&#121;&#111;u&#115;ef&#064;&#112;&#114;ak&#116;i&#115;k&#097;&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">to&#110;&#121;&#046;yo&#117;&#115;&#101;&#102;&#064;&#112;r&#097;k&#116;&#105;&#115;k&#097;.&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"489\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094051-scaled-e1729087113794-400x489.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094051-scaled-e1729087113794-400x489.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094051-scaled-e1729087113794-300x367.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094051-scaled-e1729087113794-600x733.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094051-scaled-e1729087113794-800x978.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094051-scaled-e1729087113794-1024x1251.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094051-scaled-e1729087113794-1200x1466.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094051-scaled-e1729087113794.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tAndreas Zell\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">El &amp; Energi och Larm &amp; S\u00e4kerhetsteknik<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"ma&#105;lto&#058;an&#100;&#101;&#114;&#097;s&#046;z&#101;&#108;l&#064;prak&#116;i&#115;k&#097;&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">andera&#115;&#046;z&#101;l&#108;&#064;p&#114;akt&#105;ska.&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"491\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028924-scaled-e1772618608300-400x491.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028924-scaled-e1772618608300-400x491.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028924-scaled-e1772618608300-300x368.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028924-scaled-e1772618608300-600x737.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028924-scaled-e1772618608300-800x982.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028924-scaled-e1772618608300-1024x1258.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028924-scaled-e1772618608300-1200x1474.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028924-scaled-e1772618608300.jpg 1324w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tTuija Tranberg\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Barn &amp; Fritid<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0767773638\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-777 36 38<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;ilto:&#116;&#117;i&#106;a&#046;&#116;&#114;a&#110;&#098;&#101;&#114;g&#064;prakti&#115;&#107;&#097;.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#116;&#117;i&#106;&#097;.tr&#097;n&#098;e&#114;g&#064;prakt&#105;sk&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"534\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004145449-scaled-e1729086622263-400x534.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004145449-scaled-e1729086622263-400x534.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004145449-scaled-e1729086622263-300x400.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004145449-scaled-e1729086622263-600x801.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004145449-scaled-e1729086622263-800x1067.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004145449-scaled-e1729086622263-1024x1366.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004145449-scaled-e1729086622263-1200x1601.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004145449-scaled-e1729086622263.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tCamilla Johansson\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">V\u00e5rd &amp; Omsorg och Skyddsombud<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0724523665\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">0724-523 665 <\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;a&#105;lto&#058;c&#097;m&#105;&#108;la.joh&#097;&#110;&#115;so&#110;&#064;pra&#107;&#116;i&#115;ka&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">c&#097;&#109;&#105;&#108;&#108;a.&#106;o&#104;a&#110;&#115;son&#064;&#112;r&#097;kt&#105;&#115;&#107;&#097;.&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"424\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925140444-scaled-e1729086130711-400x424.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925140444-scaled-e1729086130711-400x424.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925140444-scaled-e1729086130711-300x318.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925140444-scaled-e1729086130711-600x635.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925140444-scaled-e1729086130711-800x847.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925140444-scaled-e1729086130711-1024x1084.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925140444-scaled-e1729086130711-1200x1271.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925140444-scaled-e1729086130711.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tRosemary Starenius\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">V\u00e5rd &amp; Omsorg<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0767773103\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-777 31 03<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"ma&#105;&#108;&#116;&#111;&#058;r&#111;&#115;em&#097;&#114;y&#046;&#115;&#116;&#097;&#114;&#101;&#110;i&#117;&#115;&#064;pr&#097;&#107;&#116;i&#115;ka.s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">r&#111;&#115;em&#097;&#114;y&#046;star&#101;n&#105;&#117;&#115;&#064;pr&#097;&#107;&#116;&#105;ska.s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"440\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141105-scaled-e1729086079116-400x440.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141105-scaled-e1729086079116-400x440.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141105-scaled-e1729086079116-300x330.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141105-scaled-e1729086079116-600x660.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141105-scaled-e1729086079116-800x880.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141105-scaled-e1729086079116-1024x1127.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141105-scaled-e1729086079116-1200x1321.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926141105-scaled-e1729086079116.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tJoakim Bergstr\u00f6m\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Bygg &amp; Anl\u00e4ggning<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0790060009\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">079-006 00 09<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;il&#116;&#111;:kj&#101;&#108;lj&#111;a&#107;&#105;&#109;&#046;&#098;ergstrom&#064;&#112;r&#097;kt&#105;s&#107;a.&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#107;je&#108;&#108;&#106;&#111;a&#107;im&#046;&#098;ergstr&#111;m&#064;p&#114;a&#107;&#116;i&#115;k&#097;.&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"393\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135815-scaled-e1729866632274-400x393.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135815-scaled-e1729866632274-400x393.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135815-scaled-e1729866632274-300x295.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135815-scaled-e1729866632274-600x589.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135815-scaled-e1729866632274-800x786.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135815-scaled-e1729866632274-1024x1006.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135815-scaled-e1729866632274-1200x1178.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021135815-scaled-e1729866632274.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tKamilla Roos\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Barn &amp; Fritid<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"mailto&#058;&#107;a&#109;&#105;lla.roos&#064;p&#114;&#097;&#107;&#116;&#105;sk&#097;.s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">ka&#109;&#105;&#108;&#108;a&#046;&#114;&#111;&#111;&#115;&#064;&#112;&#114;aktis&#107;a.&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"405\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000030058-scaled-e1774601157484-400x405.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000030058-scaled-e1774601157484-400x405.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000030058-scaled-e1774601157484-300x304.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000030058-scaled-e1774601157484-600x608.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000030058-scaled-e1774601157484-800x811.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000030058-scaled-e1774601157484-1024x1037.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000030058-scaled-e1774601157484-1200x1216.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000030058-scaled-e1774601157484.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tGabriela Bengtsson\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">V\u00e5rd &amp; Omsorg<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0767773653\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-777 36 53<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;&#105;&#108;&#116;o&#058;gab&#114;&#105;&#101;&#108;&#097;.&#098;en&#103;t&#115;&#115;&#111;n2&#064;&#112;&#114;akt&#105;&#115;ka.s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">ga&#098;ri&#101;&#108;a.&#098;&#101;ng&#116;&#115;&#115;on2&#064;pra&#107;&#116;i&#115;&#107;&#097;.&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"496\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925154225-scaled-e1729085848514-400x496.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925154225-scaled-e1729085848514-400x496.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925154225-scaled-e1729085848514-300x372.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925154225-scaled-e1729085848514-600x744.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925154225-scaled-e1729085848514-800x991.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925154225-scaled-e1729085848514-1024x1269.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925154225-scaled-e1729085848514-1200x1487.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925154225-scaled-e1729085848514.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tJenny Uhlin\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Hantverk, inriktning H\u00e5r- &amp; Make up-stylist <\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0702936951\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">0702-9369 51 <\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"mai&#108;&#116;&#111;:&#106;&#101;n&#110;y&#046;u&#104;l&#105;n&#064;p&#114;&#097;k&#116;&#105;&#115;&#107;a&#046;s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#106;&#101;n&#110;y&#046;u&#104;l&#105;n&#064;pr&#097;k&#116;&#105;s&#107;a&#046;s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"463\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926142234-scaled-e1729086986541-400x463.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926142234-scaled-e1729086986541-400x463.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926142234-scaled-e1729086986541-300x347.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926142234-scaled-e1729086986541-600x694.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926142234-scaled-e1729086986541-800x925.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926142234-scaled-e1729086986541-1024x1184.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926142234-scaled-e1729086986541-1200x1388.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926142234-scaled-e1729086986541.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tPeter Achaladaya Milton\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Religion och Larm- &amp; s\u00e4kerhetsteknik<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761384933\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-138 49 33<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"mailt&#111;:&#112;&#101;&#116;&#101;r.&#109;&#105;l&#116;o&#110;&#064;&#112;r&#097;kt&#105;sk&#097;.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">pet&#101;r&#046;&#109;il&#116;&#111;n&#064;&#112;&#114;a&#107;&#116;i&#115;&#107;&#097;&#046;&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"478\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-400x478.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-400x478.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-300x358.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-600x717.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-800x956.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-1024x1224.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557-1200x1434.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241004094240-scaled-e1729086177557.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tMonique Lunde\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Hotell &amp; turism<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0707411020\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-741 10 20<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;il&#116;&#111;:&#109;oniq&#117;e.lu&#110;d&#101;&#064;&#112;r&#097;&#107;tis&#107;&#097;.s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">moniqu&#101;&#046;&#108;&#117;&#110;&#100;e&#064;pra&#107;t&#105;&#115;ka.&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"568\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000030574-1-scaled-e1755256280119-400x568.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personfoto\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000030574-1-scaled-e1755256280119-400x568.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000030574-1-scaled-e1755256280119-300x426.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000030574-1-scaled-e1755256280119-600x852.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000030574-1-scaled-e1755256280119-800x1136.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000030574-1-scaled-e1755256280119-1024x1454.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000030574-1-scaled-e1755256280119-1200x1704.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000030574-1-scaled-e1755256280119.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tAla Baban\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Barn &amp; Fritid<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0762030561\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-203 05 61<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;i&#108;to&#058;&#097;&#108;&#097;&#046;&#098;&#097;&#098;&#097;&#110;&#064;&#112;r&#097;&#107;&#116;isk&#097;.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">al&#097;&#046;baba&#110;&#064;&#112;&#114;&#097;kti&#115;&#107;a.&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"483\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021133521-scaled-e1729863542705-400x483.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021133521-scaled-e1729863542705-400x483.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021133521-scaled-e1729863542705-300x362.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021133521-scaled-e1729863542705-600x725.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021133521-scaled-e1729863542705-800x967.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021133521-scaled-e1729863542705-1024x1237.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021133521-scaled-e1729863542705-1200x1450.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/07\/20241021133521-scaled-e1729863542705.jpg 1412w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tMia Guldbrand\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Barn &amp; Fritid<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761308584\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-130 85 84<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;ai&#108;&#116;o:m&#105;a&#046;&#103;u&#108;db&#114;a&#110;&#100;&#064;prak&#116;is&#107;&#097;&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#109;&#105;a.g&#117;ld&#098;&#114;a&#110;d&#064;pr&#097;ktis&#107;&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"479\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241002143929-scaled-e1729086574260-400x479.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241002143929-scaled-e1729086574260-400x479.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241002143929-scaled-e1729086574260-300x360.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241002143929-scaled-e1729086574260-600x719.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241002143929-scaled-e1729086574260-800x959.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241002143929-scaled-e1729086574260-1024x1227.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241002143929-scaled-e1729086574260-1200x1438.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241002143929-scaled-e1729086574260.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"amneslarare yrkeslarare\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tMichael Lindfors\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Engelska &amp; F\u00f6rs\u00e4ljning och Service (f\u00f6r\u00e4ldraledig)<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0766397066\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-639 70 66<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;ilt&#111;&#058;&#109;&#105;&#099;&#104;&#097;&#101;&#108;.&#108;&#105;&#110;df&#111;rs&#064;p&#114;&#097;&#107;&#116;&#105;sk&#097;&#046;se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#109;ic&#104;&#097;el&#046;&#108;&#105;ndfors&#064;p&#114;a&#107;&#116;iska&#046;&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"427\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-400x427.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-400x427.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-300x320.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-600x641.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-800x854.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-1024x1094.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296-1200x1282.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240930154000-scaled-e1729086319296.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t\n\t\t    <div class=\"ams-contact__more u-inline-items js-load-more-btn\">\n        <button href=\"#\"\n                class=\"c-btn\"\n                data-style=\"round\"\n                data-size=\"md\"\n                data-width=\"full-mobile\"\n                data-variant=\"outline\">\n        \tVisa mer\n        <\/button>\n    <\/div>\n\n\t\t\t<\/div>\n\n\t\t\n\n<\/section>\n\n\n\n<section id=elevhalsa\n\t\t class=\"\n\t\t ams-contact\n\t\t \n\t\t c-block l-stacked\n\t\t \n\t\t \n\t\t js-load-more\n\t\t \"\n\t\t data-color-scheme=\"white\"\n\t\t\t\t\tdata-count=\"50\"\n\t\t\t\t\t\t\tdata-count-mobile=\"2\"\n\t\t\t\t>\n\t<div\n\t\t class=\"\n\t\t l-container\n\t\t l-stack l-stack-fluid-2xl\n\t\t u-pt-fluid-3xl-6xl\n\t\t u-pb-fluid-3xl-6xl\n\t\t is-center\n\t\t is-center@md\n\t\t \">\n\t\t\t\t\t<div class=\"ams-contact__intro l-stack l-stack-lg\">\n\t\t\t\t\t\n\t<h2\n\tclass=\"c-heading u-font-title-1 \"\n\tstyle=\"\">\n\t\t\n\t\t\t\t\tElevh\u00e4lsa\n\t\t\t\t\n\t<\/h2>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t    \t\n\t\t\n\t\t<ul\n\t\t\tid=\"contact-grid-6a573d2832582\"\n\t\t\tclass=\"ams-contact__list l-grid u-gap-fluid-2xl-4xl u-justify-center js-results \"\n\t\t\taria-label=\"Kontakter\"\n\t\t\tdata-filter-animation=\"off\"\n\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tChristoffer Katenda\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Elevassistent<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761108144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-110 81 44<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;a&#105;lto:&#099;hri&#115;toffe&#114;.&#107;a&#116;endadizo&#110;g&#111;&#064;&#112;&#114;&#097;k&#116;i&#115;ka&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#099;&#104;ris&#116;of&#102;&#101;&#114;.kat&#101;n&#100;&#097;di&#122;&#111;&#110;&#103;o&#064;&#112;ra&#107;t&#105;&#115;k&#097;&#046;&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"412\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-400x412.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personfoto\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-400x412.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-300x309.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-600x617.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-800x823.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-1024x1053.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-1200x1235.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419.jpg 1634w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tHakim Benchenaa\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Socialpedagog<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0703625871\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-362 58 71<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;&#105;lt&#111;:&#104;&#097;kim.&#098;&#101;&#110;&#099;&#104;e&#110;&#097;a&#064;&#112;&#114;&#097;kti&#115;ka.s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">h&#097;k&#105;m&#046;&#098;enc&#104;e&#110;a&#097;&#064;p&#114;a&#107;t&#105;sk&#097;.s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"505\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-400x505.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-400x505.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-300x379.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-600x758.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-800x1010.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-1024x1293.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-1200x1515.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tHanna Holmqvist\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Specialpedagog<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0702517362\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-251 73 62<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"mail&#116;&#111;:h&#097;&#110;&#110;&#097;.ho&#108;&#109;qv&#105;&#115;t&#064;&#112;&#114;&#097;k&#116;i&#115;k&#097;&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">han&#110;&#097;&#046;&#104;ol&#109;qvi&#115;t&#064;&#112;r&#097;ktis&#107;&#097;.&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"439\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926143718-scaled-e1729088406917-400x439.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926143718-scaled-e1729088406917-400x439.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926143718-scaled-e1729088406917-300x329.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926143718-scaled-e1729088406917-600x658.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926143718-scaled-e1729088406917-800x878.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926143718-scaled-e1729088406917-1024x1123.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926143718-scaled-e1729088406917-1200x1317.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240926143718-scaled-e1729088406917.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tIngela J\u00f6nsson\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Speciall\u00e4rare<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0720921884\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">072-092 18 84<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;i&#108;&#116;&#111;&#058;i&#110;&#103;&#101;&#108;a&#109;&#097;r&#103;a&#114;&#101;ta.&#106;&#111;&#110;s&#115;on&#064;prakt&#105;&#115;k&#097;&#046;se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#105;ng&#101;l&#097;&#109;&#097;r&#103;&#097;r&#101;&#116;a.&#106;o&#110;sson&#064;p&#114;a&#107;t&#105;ska.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"465\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925145304-scaled-e1729088313176-400x465.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925145304-scaled-e1729088313176-400x465.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925145304-scaled-e1729088313176-300x349.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925145304-scaled-e1729088313176-600x697.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925145304-scaled-e1729088313176-800x930.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925145304-scaled-e1729088313176-1024x1190.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925145304-scaled-e1729088313176-1200x1395.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925145304-scaled-e1729088313176.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tNarin Lordini\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Skolkurator<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0703172973\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-317 29 73<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"ma&#105;lto:nar&#105;n&#046;&#108;o&#114;&#100;&#105;&#110;&#105;&#064;&#112;ra&#107;&#116;&#105;s&#107;&#097;.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#110;ar&#105;&#110;&#046;&#108;&#111;&#114;din&#105;&#064;p&#114;a&#107;t&#105;&#115;&#107;&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"510\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028789-scaled-e1772618892740-400x510.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028789-scaled-e1772618892740-400x510.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028789-scaled-e1772618892740-300x382.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028789-scaled-e1772618892740-600x765.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028789-scaled-e1772618892740-800x1020.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028789-scaled-e1772618892740-1024x1305.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028789-scaled-e1772618892740-1200x1530.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028789-scaled-e1772618892740.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tAlbina Tuzovic\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Skolsk\u00f6terska<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0720921883\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">072-092 18 83<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;&#097;i&#108;&#116;&#111;:a&#108;&#098;i&#110;&#097;.&#116;u&#122;o&#118;ic&#064;&#112;&#114;&#097;k&#116;&#105;s&#107;&#097;.&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">al&#098;&#105;n&#097;&#046;t&#117;z&#111;vi&#099;&#064;pr&#097;kt&#105;&#115;k&#097;&#046;&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"456\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241009134435-scaled-e1729088659105-400x456.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241009134435-scaled-e1729088659105-400x456.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241009134435-scaled-e1729088659105-300x342.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241009134435-scaled-e1729088659105-600x683.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241009134435-scaled-e1729088659105-800x911.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241009134435-scaled-e1729088659105-1024x1166.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241009134435-scaled-e1729088659105-1200x1367.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20241009134435-scaled-e1729088659105.jpg 1288w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa ledning\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tCaroline Sj\u00f6kvist\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Bitr\u00e4dande rektor &amp; Specialpedagog<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0702309244\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">0702-309244  <\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"ma&#105;lt&#111;:&#099;&#097;&#114;&#111;&#108;i&#110;&#101;.&#115;j&#111;k&#118;is&#116;&#064;&#112;&#114;akt&#105;sk&#097;&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">c&#097;r&#111;&#108;&#105;n&#101;&#046;s&#106;o&#107;vi&#115;&#116;&#064;p&#114;ak&#116;i&#115;k&#097;.&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"413\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-400x413.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-400x413.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-300x310.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-600x620.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-800x826.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-1024x1057.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318-1200x1239.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925152053-scaled-e1729086944318.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tDidier Muvemba\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Socialpedagog<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761037719\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-103 77 19<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;i&#108;to&#058;d&#105;&#100;&#105;&#101;&#114;.m&#117;&#118;&#101;mba&#064;&#112;ra&#107;&#116;i&#115;&#107;a&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">did&#105;er.&#109;&#117;&#118;&#101;&#109;&#098;&#097;&#064;&#112;&#114;a&#107;t&#105;&#115;k&#097;.&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"408\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-400x408.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-400x408.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-300x306.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-600x612.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-800x817.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-1024x1045.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-1200x1225.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tHeradi Rashidi\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Elevassistent<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761055974\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-105 59 74<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;ai&#108;to&#058;&#104;&#101;&#114;&#097;&#100;&#105;&#046;&#114;&#097;s&#104;&#105;&#100;i&#064;&#112;raktis&#107;a&#046;&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#104;&#101;&#114;a&#100;&#105;.&#114;&#097;&#115;&#104;&#105;di&#064;&#112;&#114;&#097;k&#116;i&#115;k&#097;.s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"479\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-400x479.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-400x479.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-300x360.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-600x719.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-800x959.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-1024x1227.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-1200x1438.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tLisa Scheffer\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Studie- och yrkesv\u00e4gledare<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0767644398\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-764 43 98<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;a&#105;&#108;&#116;o:l&#105;&#115;&#097;&#109;ic&#104;&#101;ll&#101;&#046;&#115;&#099;&#104;&#101;f&#102;&#101;&#114;&#064;pr&#097;&#107;t&#105;sk&#097;.se\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">lisa&#109;i&#099;h&#101;l&#108;e&#046;&#115;ch&#101;f&#102;&#101;r&#064;&#112;&#114;a&#107;&#116;&#105;sk&#097;&#046;&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"614\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028796-400x614.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028796-400x614.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028796-300x460.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028796-600x921.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028796-800x1228.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028796-1024x1572.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028796-1200x1842.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028796-scaled.jpg 1668w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tNathalie Blomqvist\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Studie- och yrkesv\u00e4gledare<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"240\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/2023\/11\/kontactplaceholder.png\" class=\"u-radius-round u-ratio-landscape\" alt=\"Avatarbild\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tSara Westlin\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Skollogoped<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0767774130\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-777 41 30<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"ma&#105;l&#116;o&#058;s&#097;ra&#046;we&#115;tlin&#064;p&#114;&#097;k&#116;&#105;s&#107;a&#046;&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">s&#097;ra&#046;w&#101;s&#116;&#108;&#105;&#110;&#064;prakt&#105;&#115;&#107;a.s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"462\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000021092-scaled-e1756284040597-400x462.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personfoto\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000021092-scaled-e1756284040597-400x462.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000021092-scaled-e1756284040597-300x346.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000021092-scaled-e1756284040597-600x692.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000021092-scaled-e1756284040597-800x923.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000021092-scaled-e1756284040597-1024x1182.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000021092-scaled-e1756284040597-1200x1385.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/1000021092-scaled-e1756284040597.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t\n\t\t    <div class=\"ams-contact__more u-inline-items js-load-more-btn\">\n        <button href=\"#\"\n                class=\"c-btn\"\n                data-style=\"round\"\n                data-size=\"md\"\n                data-width=\"full-mobile\"\n                data-variant=\"outline\">\n        \tVisa mer\n        <\/button>\n    <\/div>\n\n\t\t\t<\/div>\n\n\t\t\n\n<\/section>\n\n\n\n<section \n\t\t class=\"\n\t\t ams-contact\n\t\t \n\t\t c-block l-stacked\n\t\t \n\t\t \n\t\t js-load-more\n\t\t \"\n\t\t data-color-scheme=\"white\"\n\t\t\t\t\tdata-count=\"50\"\n\t\t\t\t\t\t\tdata-count-mobile=\"2\"\n\t\t\t\t>\n\t<div\n\t\t class=\"\n\t\t l-container\n\t\t l-stack l-stack-fluid-2xl\n\t\t u-pt-fluid-3xl-6xl\n\t\t u-pb-fluid-3xl-6xl\n\t\t is-center\n\t\t is-center@md\n\t\t \">\n\t\t\t\t\t<div class=\"ams-contact__intro l-stack l-stack-lg\">\n\t\t\t\t\t\n\t<h2\n\tclass=\"c-heading u-font-title-1 \"\n\tstyle=\"\">\n\t\t\n\t\t\t\t\tElevservice\n\t\t\t\t\n\t<\/h2>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t    \t\n\t\t\n\t\t<ul\n\t\t\tid=\"contact-grid-6a573d283be2a\"\n\t\t\tclass=\"ams-contact__list l-grid u-gap-fluid-2xl-4xl u-justify-center js-results \"\n\t\t\taria-label=\"Kontakter\"\n\t\t\tdata-filter-animation=\"off\"\n\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tChristoffer Katenda\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Elevassistent<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761108144\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-110 81 44<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"mailt&#111;&#058;&#099;h&#114;&#105;s&#116;o&#102;&#102;e&#114;&#046;&#107;a&#116;end&#097;di&#122;&#111;&#110;&#103;o&#064;pr&#097;&#107;&#116;iska.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">ch&#114;is&#116;&#111;&#102;fe&#114;.&#107;at&#101;&#110;&#100;a&#100;izo&#110;go&#064;prakt&#105;ska.s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"412\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-400x412.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personfoto\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-400x412.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-300x309.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-600x617.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-800x823.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-1024x1053.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419-1200x1235.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2025\/08\/202508151246381-scaled-e1755256504419.jpg 1634w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tHakim Benchenaa\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Socialpedagog<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0703625871\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-362 58 71<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;&#105;&#108;to:haki&#109;&#046;&#098;en&#099;he&#110;a&#097;&#064;&#112;ra&#107;&#116;isk&#097;&#046;&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#104;a&#107;&#105;&#109;&#046;&#098;&#101;&#110;c&#104;en&#097;&#097;&#064;pr&#097;k&#116;i&#115;&#107;&#097;.s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"505\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-400x505.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-400x505.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-300x379.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-600x758.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-800x1010.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-1024x1293.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392-1200x1515.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925150512-scaled-e1729088451392.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tDidier Muvemba\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Socialpedagog<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761037719\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-103 77 19<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"ma&#105;lto&#058;di&#100;&#105;er&#046;&#109;&#117;&#118;emb&#097;&#064;&#112;&#114;&#097;&#107;&#116;i&#115;k&#097;.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#100;i&#100;&#105;e&#114;.muve&#109;ba&#064;&#112;r&#097;kt&#105;s&#107;&#097;.se<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"408\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-400x408.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-400x408.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-300x306.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-600x612.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-800x817.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-1024x1045.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903-1200x1225.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155722-scaled-e1729086417903.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"administration elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tEsmeralda Wall\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Skolkoordinator &amp; APL-samordnare<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0706430551\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">070-643 05 51<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;ilto:e&#115;&#109;&#101;&#114;a&#108;&#100;&#097;&#046;wa&#108;&#108;&#064;&#112;&#114;&#097;&#107;&#116;&#105;&#115;ka.s&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">esme&#114;a&#108;d&#097;.&#119;a&#108;l&#064;&#112;&#114;a&#107;&#116;isk&#097;.&#115;e<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"513\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-400x513.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-400x513.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-300x385.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-600x770.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-800x1027.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-1024x1314.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942-1200x1540.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/03\/1000028786-scaled-e1772618969942.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"administration elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tHelena Andersson\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Skoladministrat\u00f6r &amp; Internationaliseringsansvarig<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761016523\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-101 65 23<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"m&#097;i&#108;&#116;o:helen&#097;.&#097;n&#100;ers&#115;on&#064;&#112;r&#097;&#107;&#116;i&#115;&#107;&#097;&#046;&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">h&#101;&#108;&#101;na&#046;&#097;&#110;de&#114;&#115;s&#111;&#110;&#064;p&#114;akt&#105;sk&#097;.s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"503\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-400x503.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-400x503.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-300x377.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-600x754.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-800x1006.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-1024x1287.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203-1200x1509.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925135513-scaled-e1729085902203.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"elevhalsa elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tHeradi Rashidi\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Elevassistent<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0761055974\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-105 59 74<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"&#109;ai&#108;to:&#104;e&#114;adi&#046;&#114;&#097;&#115;h&#105;&#100;&#105;&#064;&#112;&#114;a&#107;&#116;i&#115;k&#097;.&#115;e\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">h&#101;ra&#100;i.ra&#115;&#104;&#105;di&#064;pr&#097;k&#116;&#105;s&#107;a.&#115;&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"479\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-400x479.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-400x479.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-300x360.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-600x719.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-800x959.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-1024x1227.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850-1200x1438.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2026\/02\/202602180912331-1-scaled-e1772618711850.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<li class=\"l-col-6@md l-col-4@lg \" data-filter=\"administration elevservice\">\n\t\t\t\t\t<article class=\"c-card \" data-variant=\"neutral\">\n\t\t\t\t\t\t<div class=\"c-card__content u-text-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"c-card__title u-font-title-3\">\n\t\t\t\t\t\t\t\t\tMax Nordin\n\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"position u-font-body\">Skolbibliotekarie &amp; Vaktm\u00e4stare<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-info u-font-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"phone\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"tel:0767729298\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">076-772 92 98<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"email\"><a\n\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"ma&#105;lto:&#109;&#097;&#120;.&#110;&#111;r&#100;i&#110;&#064;pr&#097;&#107;&#116;&#105;s&#107;&#097;.&#115;&#101;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"u-text-link\">&#109;ax&#046;&#110;&#111;&#114;&#100;in&#064;pr&#097;k&#116;isk&#097;&#046;s&#101;<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"c-card__media\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"467\" src=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-400x467.jpg\" class=\"u-radius-round u-ratio-landscape\" alt=\"Personportr\u00e4tt\" sizes=\"(max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-400x467.jpg 400w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-300x351.jpg 300w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-600x701.jpg 600w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-800x935.jpg 800w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-1024x1197.jpg 1024w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139-1200x1402.jpg 1200w, https:\/\/praktiska.se\/wp-content\/uploads\/sites\/33\/2024\/09\/20240925155858-scaled-e1729086476139.jpg 1442w\" \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/article>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t\n\t\t    <div class=\"ams-contact__more u-inline-items js-load-more-btn\">\n        <button href=\"#\"\n                class=\"c-btn\"\n                data-style=\"round\"\n                data-size=\"md\"\n                data-width=\"full-mobile\"\n                data-variant=\"outline\">\n        \tVisa mer\n        <\/button>\n    <\/div>\n\n\t\t\t<\/div>\n\n\t\t\n\n<\/section>\n\n\n\n<section  class=\"ams-cta ams-cta--stacked c-block l-stacked\" data-color-scheme=\"orange\">\n\t<div class=\"l-container-narrow l-stack l-stack-fluid-2xl u-pt-fluid-3xl-6xl u-pb-fluid-3xl-6xl is-center is-center@md\">\n\t\t\t\t\t<div class=\"ams-cta__intro l-stack l-stack-lg\">\n\t\t\t\t\t\n\t<h2\n\tclass=\"c-heading u-font-title-1 \"\n\tstyle=\"\">\n\t\t\n\t\t\t\t\tHar du synpunkter p\u00e5 v\u00e5r verksamhet?\n\t\t\t\t\n\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t<div class=\"c-text l-stack u-cs-xl u-font-body\">\n\t\t\t\t\t\t<p><span data-sheets-root=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Vi \u00e4r alltid intresserade av f\u00e5 veta vad som fungerar bra, men \u00e4ven det som fungerar mindre bra. Klicka dig vidare f\u00f6r att l\u00e4sa mer. &quot;}\" data-sheets-userformat=\"{&quot;2&quot;:899,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:14281427},&quot;10&quot;:0,&quot;11&quot;:4,&quot;12&quot;:0}\">Vi \u00e4r alltid intresserade av f\u00e5 veta vad som fungerar bra, men \u00e4ven det som fungerar mindre bra. Klicka dig vidare f\u00f6r att l\u00e4sa mer. <\/span><\/p>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\t<div class=\"ams-cta__action u-inline-items\">\n\t\t\t\t\t\t\t\n\n\n\n<a href=\"https:\/\/praktiska.se\/vart-kvalitetsarbete\/lamna-synpunkter\/\"\n\t\n\tclass=\"c-btn \"\n\tdata-style=\"round\"\n\tdata-size=\"md\"\n\tdata-width=\"full-mobile\"\n\tdata-variant=\"default\"\n\ttarget=\"_blank\">\n\t\t\t<span class=\"label\"> L\u00e4mna synpunkter till oss<\/span>\n\t\t\t\t\t<i class=\"fa fa-external-link\" data-icon><\/i>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\n\n\t\t\n\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"archive-personal.php","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kontakta oss - Praktiska Gymnasiet Stockholm Liljeholmen<\/title>\n<meta name=\"description\" content=\"H\u00e4r hittar du kontaktuppgifter till skolans personal. H\u00e4r finns ocks\u00e5 bes\u00f6ksadress och postadress till skolan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kontakta oss - Praktiska Gymnasiet Stockholm Liljeholmen\" \/>\n<meta property=\"og:description\" content=\"H\u00e4r hittar du kontaktuppgifter till skolans personal. H\u00e4r finns ocks\u00e5 bes\u00f6ksadress och postadress till skolan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/\" \/>\n<meta property=\"og:site_name\" content=\"Stockholm Liljeholmen\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-17T12:28:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Kontakta oss - Praktiska Gymnasiet Stockholm Liljeholmen\" \/>\n<meta name=\"twitter:description\" content=\"H\u00e4r hittar du kontaktuppgifter till skolans personal. H\u00e4r finns ocks\u00e5 bes\u00f6ksadress och postadress till skolan.\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/\",\"url\":\"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/\",\"name\":\"Kontakta oss - Praktiska Gymnasiet Stockholm Liljeholmen\",\"isPartOf\":{\"@id\":\"https:\/\/praktiska.se\/stockholm-liljeholmen\/#website\"},\"datePublished\":\"2023-02-14T10:25:26+00:00\",\"dateModified\":\"2025-02-17T12:28:52+00:00\",\"description\":\"H\u00e4r hittar du kontaktuppgifter till skolans personal. H\u00e4r finns ocks\u00e5 bes\u00f6ksadress och postadress till skolan.\",\"breadcrumb\":{\"@id\":\"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\/\/praktiska.se\/stockholm-liljeholmen\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kontakta oss\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/praktiska.se\/stockholm-liljeholmen\/#website\",\"url\":\"https:\/\/praktiska.se\/stockholm-liljeholmen\/\",\"name\":\"Stockholm Liljeholmen\",\"description\":\"Vi utbildar framtidens arbetskraft\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/praktiska.se\/stockholm-liljeholmen\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sv-SE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kontakta oss - Praktiska Gymnasiet Stockholm Liljeholmen","description":"H\u00e4r hittar du kontaktuppgifter till skolans personal. H\u00e4r finns ocks\u00e5 bes\u00f6ksadress och postadress till skolan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/","og_locale":"sv_SE","og_type":"article","og_title":"Kontakta oss - Praktiska Gymnasiet Stockholm Liljeholmen","og_description":"H\u00e4r hittar du kontaktuppgifter till skolans personal. H\u00e4r finns ocks\u00e5 bes\u00f6ksadress och postadress till skolan.","og_url":"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/","og_site_name":"Stockholm Liljeholmen","article_modified_time":"2025-02-17T12:28:52+00:00","twitter_card":"summary_large_image","twitter_title":"Kontakta oss - Praktiska Gymnasiet Stockholm Liljeholmen","twitter_description":"H\u00e4r hittar du kontaktuppgifter till skolans personal. H\u00e4r finns ocks\u00e5 bes\u00f6ksadress och postadress till skolan.","twitter_misc":{"Est. reading time":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/","url":"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/","name":"Kontakta oss - Praktiska Gymnasiet Stockholm Liljeholmen","isPartOf":{"@id":"https:\/\/praktiska.se\/stockholm-liljeholmen\/#website"},"datePublished":"2023-02-14T10:25:26+00:00","dateModified":"2025-02-17T12:28:52+00:00","description":"H\u00e4r hittar du kontaktuppgifter till skolans personal. H\u00e4r finns ocks\u00e5 bes\u00f6ksadress och postadress till skolan.","breadcrumb":{"@id":"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/praktiska.se\/stockholm-liljeholmen\/kontakt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/praktiska.se\/stockholm-liljeholmen\/"},{"@type":"ListItem","position":2,"name":"Kontakta oss"}]},{"@type":"WebSite","@id":"https:\/\/praktiska.se\/stockholm-liljeholmen\/#website","url":"https:\/\/praktiska.se\/stockholm-liljeholmen\/","name":"Stockholm Liljeholmen","description":"Vi utbildar framtidens arbetskraft","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/praktiska.se\/stockholm-liljeholmen\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sv-SE"}]}},"_links":{"self":[{"href":"https:\/\/praktiska.se\/stockholm-liljeholmen\/wp-json\/wp\/v2\/pages\/94"}],"collection":[{"href":"https:\/\/praktiska.se\/stockholm-liljeholmen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/praktiska.se\/stockholm-liljeholmen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/praktiska.se\/stockholm-liljeholmen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/praktiska.se\/stockholm-liljeholmen\/wp-json\/wp\/v2\/comments?post=94"}],"version-history":[{"count":10,"href":"https:\/\/praktiska.se\/stockholm-liljeholmen\/wp-json\/wp\/v2\/pages\/94\/revisions"}],"predecessor-version":[{"id":3580,"href":"https:\/\/praktiska.se\/stockholm-liljeholmen\/wp-json\/wp\/v2\/pages\/94\/revisions\/3580"}],"wp:attachment":[{"href":"https:\/\/praktiska.se\/stockholm-liljeholmen\/wp-json\/wp\/v2\/media?parent=94"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}